{"id":2980,"date":"2025-10-04T12:56:51","date_gmt":"2025-10-04T11:56:51","guid":{"rendered":"https:\/\/paulaonwheels.org\/?post_type=tours&#038;p=2980"},"modified":"2025-10-28T22:36:28","modified_gmt":"2025-10-28T22:36:28","slug":"belem-tour","status":"publish","type":"tours","link":"https:\/\/paulaonwheels.org\/pt\/tour\/belem-tour\/","title":{"rendered":"05. Bel\u00e9m"},"content":{"rendered":"<p>Uma viagem ao bairro da Expans\u00e3o Mar\u00edtima Portuguesa, Bel\u00e9m. Nos s\u00e9culos XV e XVI, era daqui que partiam as caravelas e onde chegavam as not\u00edcias dos descobrimentos. Aqui eram celebradas missas antes da partida das frotas e a praia era ent\u00e3o conhecida como a \u201cPraia das L\u00e1grimas\u201d. Outrora um importante porto, Bel\u00e9m sofreu uma transforma\u00e7\u00e3o ap\u00f3s o terramoto de 1755 e, mais recentemente, um novo desenho urbano com a realiza\u00e7\u00e3o da Exposi\u00e7\u00e3o do Mundo Portugu\u00eas pelo Estado Novo em 1940. Atualmente revitalizada, esta zona ribeirinha tornou-se uma agrad\u00e1vel \u00e1rea de lazer e um importante p\u00f3lo cultural e museol\u00f3gico. Pelo caminho, passaremos pelo Mosteiro dos Jer\u00f3nimos e pela Torre de Bel\u00e9m (monumentos classificados pela Unesco), provaremos os famosos past\u00e9is de Bel\u00e9m, visitaremos o miradouro da Ermida de S\u00e3o Jer\u00f3nimo, o monumento de homenagem aos feitos dos navegadores portugueses (o Padr\u00e3o) e o mais recente museu de Lisboa, o MAAT. Regressamos ao longo do rio, passando pelas Docas. <\/p>\n\n\n\n<p>\u26a0\ufe0f <strong>At\u00e9 6 pessoas se forem magras.<\/strong><\/p>\n\n\n\n<p><strong>Aten\u00e7\u00e3o: Os percursos sugeridos podem variar devido \u00e0s condi\u00e7\u00f5es de tr\u00e2nsito, eventos locais ou prefer\u00eancias do cliente. O nosso objetivo \u00e9 proporcionar uma experi\u00eancia agrad\u00e1vel e informativa que possa ser adaptada - sempre que poss\u00edvel - aos interesses de cada visitante.<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><\/p>","protected":false},"excerpt":{"rendered":"<p>A journey to the neighborhood of the Portuguese Maritime Expansion, Bel\u00e9m. In the 15th and 16th centuries, it was from here that the caravels set sail and where news of the discoveries arrived. Masses were celebrated here before the fleets departed, and the beach was then known as the &#8220;Tears Beach.&#8221; Once an important harbor, [&hellip;]<\/p>","protected":false},"featured_media":3013,"parent":0,"comment_status":"open","ping_status":"closed","template":"","tour-types":[],"class_list":["post-2980","tours","type-tours","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/paulaonwheels.org\/pt\/wp-json\/wp\/v2\/tours\/2980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paulaonwheels.org\/pt\/wp-json\/wp\/v2\/tours"}],"about":[{"href":"https:\/\/paulaonwheels.org\/pt\/wp-json\/wp\/v2\/types\/tours"}],"replies":[{"embeddable":true,"href":"https:\/\/paulaonwheels.org\/pt\/wp-json\/wp\/v2\/comments?post=2980"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paulaonwheels.org\/pt\/wp-json\/wp\/v2\/media\/3013"}],"wp:attachment":[{"href":"https:\/\/paulaonwheels.org\/pt\/wp-json\/wp\/v2\/media?parent=2980"}],"wp:term":[{"taxonomy":"tour-types","embeddable":true,"href":"https:\/\/paulaonwheels.org\/pt\/wp-json\/wp\/v2\/tour-types?post=2980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}