{"id":2981,"date":"2025-10-01T12:58:01","date_gmt":"2025-10-01T11:58:01","guid":{"rendered":"https:\/\/paulaonwheels.org\/?post_type=tours&#038;p=2981"},"modified":"2025-10-28T22:37:36","modified_gmt":"2025-10-28T22:37:36","slug":"make-your-tour","status":"publish","type":"tours","link":"https:\/\/paulaonwheels.org\/es\/tour\/make-your-tour\/","title":{"rendered":"08. Cementerios"},"content":{"rendered":"<p>Un paseo por Estrela, pasando por su imponente Bas\u00edlica y el encantador barrio de Campo de Ourique, culminando en el hermoso cementerio rom\u00e1ntico del siglo XIX, Prazeres. Los cementerios son lugares que atraen por su arquitectura, arte, historia, simbolismo y memoria. Tambi\u00e9n son fuentes inagotables de inspiraci\u00f3n fotogr\u00e1fica y serenidad. Comprender c\u00f3mo se organiza la \"ciudad de los muertos\", c\u00f3mo influye en ella la ciudad de los vivos y viceversa, y descubrir las peculiaridades de los cementerios portugueses son algunos de los puntos de inter\u00e9s de este recorrido. Se trata de una experiencia original y sin duda sorprendente, una especie de encuentro entre la vida y la \"eternidad\". Por no hablar de la sorprendente vista panor\u00e1mica que \"esconde\" el cementerio. Como alternativa al cementerio de Prazeres, tenemos el Alto de S.Jo\u00e3o como opci\u00f3n. <\/p>\n\n\n\n<p>\u26a0\ufe0f <strong>Hasta 6 personas si son delgadas.<\/strong><\/p>\n\n\n\n<p><strong>Atenci\u00f3n: Las rutas sugeridas pueden variar debido a las condiciones del tr\u00e1fico, eventos locales o preferencias de los clientes. Nuestro objetivo es ofrecer una experiencia agradable e informativa que pueda adaptarse -siempre que sea posible- a los intereses de cada visitante.<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><\/p>","protected":false},"excerpt":{"rendered":"<p>A stroll through Estrela, passing by its imposing Basilica and the charming neighborhood of Campo de Ourique, culminating in the beautiful romantic cemetery from the 19th century, Prazeres. Cemeteries are places that attract with their architecture, art, history, symbolism, and memory. They are also endless sources of photographic inspiration and serenity. Understanding how the &#8220;city [&hellip;]<\/p>","protected":false},"featured_media":3353,"parent":0,"comment_status":"open","ping_status":"closed","template":"","tour-types":[],"class_list":["post-2981","tours","type-tours","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/paulaonwheels.org\/es\/wp-json\/wp\/v2\/tours\/2981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paulaonwheels.org\/es\/wp-json\/wp\/v2\/tours"}],"about":[{"href":"https:\/\/paulaonwheels.org\/es\/wp-json\/wp\/v2\/types\/tours"}],"replies":[{"embeddable":true,"href":"https:\/\/paulaonwheels.org\/es\/wp-json\/wp\/v2\/comments?post=2981"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paulaonwheels.org\/es\/wp-json\/wp\/v2\/media\/3353"}],"wp:attachment":[{"href":"https:\/\/paulaonwheels.org\/es\/wp-json\/wp\/v2\/media?parent=2981"}],"wp:term":[{"taxonomy":"tour-types","embeddable":true,"href":"https:\/\/paulaonwheels.org\/es\/wp-json\/wp\/v2\/tour-types?post=2981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}